{"id":4298,"date":"2025-03-26T11:12:21","date_gmt":"2025-03-26T11:12:21","guid":{"rendered":"https:\/\/gardeniser-academy.eu\/module\/lp3-m3-zusammen-den-garten-gruenden"},"modified":"2025-08-05T10:39:15","modified_gmt":"2025-08-05T10:39:15","slug":"lp3-m3-zusammen-den-garten-gruenden","status":"publish","type":"module","link":"https:\/\/gardeniser-academy.eu\/de\/module\/lp3-m3-zusammen-den-garten-gruenden","title":{"rendered":"LP3 M3: Zusammen Den Garten Gr\u00fcnden"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4298\" class=\"elementor elementor-4298 elementor-3708\" data-elementor-post-type=\"module\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afc2c76 e-flex e-con-boxed e-con e-parent\" data-id=\"afc2c76\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9264aef elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"9264aef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Einleitung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89b2dda elementor-widget elementor-widget-text-editor\" data-id=\"89b2dda\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In dieser Phase, die die letzte und keineswegs die unwichtigste ist, da sie die erste Phase bei der Einrichtung des Gartens darstellt, bist du in der Position des Vermittlers. Als solcher besteht deine Aufgabe darin, die Gruppe bei der Entwicklung der Materialien anzuleiten, die f\u00fcr die Verwirklichung des Gartens erforderlich sind, wie z. B. das Rahmendokument, die Charta mit ihren Werten und das Modell des Gartens. Dein Ziel wird es sein, diese Elemente zusammenzuf\u00fchren, um das Projektdokument zu erstellen. Du wirst deinen Ansatz mit den Instrumenten der Volksbildung unterst\u00fctzen.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f41705a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f41705a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lektionen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5512357 lp-ctnt elementor-widget elementor-widget-n-accordion\" data-id=\"5512357\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:300,&quot;sizes&quot;:[]},&quot;max_items_expended&quot;:&quot;one&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8920\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8920\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> L1. Kommunizieren, um das Bewusstsein f\u00fcr das Projekt zu erh\u00f6hen  <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8920\" class=\"elementor-element elementor-element-22e278a e-con-full e-flex e-con e-child\" data-id=\"22e278a\" data-element_type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8920\" class=\"elementor-element elementor-element-cf4d4f7 e-flex e-con-boxed e-con e-child\" data-id=\"cf4d4f7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a9bd42 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"3a9bd42\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Kommunikation \u00fcber das Projekt<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ceff744 elementor-widget elementor-widget-text-editor\" data-id=\"ceff744\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Die Kommunikation des Projekts an die \u00d6ffentlichkeit ist ein entscheidender Schritt, um Interesse zu wecken und neue Interessengruppen zu mobilisieren.<\/span><\/p><p><span style=\"font-weight: 400;\">Hier sind einige Strategien zur Bewerbung des Projekts:<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a94b9a2 elementor-widget elementor-widget-n-accordion\" data-id=\"a94b9a2\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1770\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1770\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 1. Erstelle auff\u00e4lliges Grafikmaterial (A4-Poster, A5-Flyer, Computergrafiken usw.). <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8920 e-n-accordion-item-1770\" class=\"elementor-element elementor-element-a6fa10e e-con-full e-flex e-con e-child\" data-id=\"a6fa10e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f2b3883 elementor-widget elementor-widget-text-editor\" data-id=\"f2b3883\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Du kannst entweder:<\/p><ul><li>freih\u00e4ndig zeichnen oder Tools wie CANVA, WORD &#8230; verwenden.<\/li><li>in Briefk\u00e4sten verteilt oder pers\u00f6nlich \u00fcbergeben in stark frequentierten Bereichen (Rathaus, Schulen, B\u00e4ckereien usw.) ausgeh\u00e4ngt.<\/li><li>Die entmaterialisierte Version wird in den sozialen Netzwerken geteilt.<\/li><li>Ben\u00f6tigte Materialien: Papier, Kopierer, Computer usw.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1771\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1771\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 2. Versenden von Pressemitteilungen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8920 e-n-accordion-item-1771\" class=\"elementor-element elementor-element-7ab8dce e-con-full e-flex e-con e-child\" data-id=\"7ab8dce\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6071f56 elementor-widget elementor-widget-text-editor\" data-id=\"6071f56\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Erstelle einen Artikel f\u00fcr die lokale Presse (z. B. die Rathauszeitung). Wir empfehlen dir, den Artikel selbst zu schreiben, damit er vollst\u00e4ndig ver\u00f6ffentlicht werden kann. Die Elemente des Projekt-Pitchs k\u00f6nnen dir beim Schreiben helfen.  <\/p><p>Wenn dein Projekt innovativ ist, k\u00f6nnten einige Medien daran interessiert sein. Schreibe eine Pressemitteilung und sende sie an Fachjournalisten oder Blogs. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1772\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1772\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 3. Ver\u00f6ffentlichung in sozialen Netzwerken: Facebook, Instagram,... <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8920 e-n-accordion-item-1772\" class=\"elementor-element elementor-element-780bd94 e-con-full e-flex e-con e-child\" data-id=\"780bd94\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a559f2 elementor-widget elementor-widget-text-editor\" data-id=\"2a559f2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Dank sozialer Netzwerke wird deine Kommunikation breiter und erm\u00f6glicht es dir auch, bestimmte Nutzergruppen nach ihren Interessen oder ihrem Standort anzusprechen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1773\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1773\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 4. Nutzung von Mundpropaganda und Botschaftern <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8920 e-n-accordion-item-1773\" class=\"elementor-element elementor-element-bdd2231 e-flex e-con-boxed e-con e-child\" data-id=\"bdd2231\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-771e35b elementor-widget elementor-widget-text-editor\" data-id=\"771e35b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Ermutige die Menschen, die bereits an dem Projekt beteiligt sind, die Botschaft zu verbreiten. Du kannst auch Botschafter ernennen. Einflussreiche Personen k\u00f6nnen das Projekt aktiv unterst\u00fctzen und deine Informationen in ihren eigenen Netzwerken teilen.  <\/span><\/p><p><span style=\"font-weight: 400;\">Jede dieser Methoden kann einzeln oder in Kombination angewendet werden, um die Sichtbarkeit deines Projekts zu maximieren.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1774\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1774\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 5. Organisieren eines Treffens <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8920 e-n-accordion-item-1774\" class=\"elementor-element elementor-element-31abbd2 e-flex e-con-boxed e-con e-child\" data-id=\"31abbd2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-147de6d elementor-widget elementor-widget-text-editor\" data-id=\"147de6d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Idealerweise solltest du ein erstes pers\u00f6nliches <b>Treffen organisieren, um die Grundz\u00fcge des Projekts<\/b>, wie im Rahmendokument beschrieben, vorzustellen.<\/p><p>Nutzt die Gelegenheit, um bei einem kleinen Imbiss mit den Teilnehmern ins Gespr\u00e4ch zu kommen &#8230;<\/p><p>Damit euer Treffen ein Erfolg wird, ben\u00f6tigt ihr die folgenden logistischen Ressourcen:<\/p><ul><li>Versammlungsraum<\/li><li>Overheadprojektor oder nicht<\/li><li>B\u00fcromaterial<\/li><li>Computer<\/li><li>Getr\u00e4nke und selbstgebackener Kuchen f\u00fcr die gesellige Runde &#8230;<\/li><\/ul><p>Personelle Ressourcen:<\/p><ul><li>Freiwillige mit Kommunikationsf\u00e4higkeiten<\/li><li>Freiwillige zum Abschleppen.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3547ec9 elementor-widget elementor-widget-text-editor\" data-id=\"3547ec9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jetzt schlagen wir euch eine Aktivit\u00e4t vor, mit der ihr die Kommunikation f\u00fcr euer Projekt des Gemeinschaftsgartens verbessern k\u00f6nnt: Ihr werdet gebeten, einen Flyer zu erstellen, um Menschen zu einem Pr\u00e4sentationstreffen einzuladen. Dabei m\u00fcsst ihr euer eigenes Projekt und den Kontext des Gartens ber\u00fccksichtigen: In welchem Viertel? Welche Zielgruppe wollt ihr erreichen? Wie alt sind die Menschen? Hast du irgendwelche Erwartungen? Ist der Treffpunkt zug\u00e4nglich? Ist es die richtige Tageszeit (Rentner haben tags\u00fcber Zeit, aber normalerweise sind Menschen zwischen 25 und 60 Jahren bei der Arbeit und haben nur abends und am Wochenende Zeit)?      <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-598b0ee elementor-align-center elementor-widget elementor-widget-button\" data-id=\"598b0ee\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/gardeniser-academy.eu\/de\/lp3_m3_l1_a1\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Making a flyer<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8921\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8921\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> L2. Vom Feld In Den Garten - mit Permakultur-Werkzeugen  <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8921\" class=\"elementor-element elementor-element-e7f6be7 e-con-full e-flex e-con e-child\" data-id=\"e7f6be7\" data-element_type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8921\" class=\"elementor-element elementor-element-33ef978 e-flex e-con-boxed e-con e-child\" data-id=\"33ef978\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea432a4 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ea432a4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Einf\u00fchrung in die Permakultur<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04a9b14 elementor-widget__width-initial dce_masking-none elementor-widget elementor-widget-video\" data-id=\"04a9b14\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=Syw1yfaWieQ&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a594b8e elementor-widget elementor-widget-text-editor\" data-id=\"a594b8e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: 1rem;\">In dieser Lektion wirst du einige Werkzeuge aus dem Permakultur-Ansatz kennenlernen, die du in einem Gemeinschaftsgartenprojekt anwenden kannst. Diese Werkzeuge repr\u00e4sentieren die Ethik und die Werte der Permakultur, wie sie von David Holmgren definiert wurden. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-advanced-background-color=\"#86CA6B\" class=\"elementor-element elementor-element-5920eb9 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"5920eb9\" data-element_type=\"widget\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"93458105\" aria-label=\"Tabs. Open items with Enter or Space, close with Escape and navigate using the Arrow keys.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-934581051\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-934581051\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t1. Die Permakultur Blume \t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-934581052\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-934581052\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t2. Permakultur-Ethik\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-934581053\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-934581053\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t3. Die 12 Prinzipien der Permakultur\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-934581054\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-934581054\" style=\"--n-tabs-title-order: 4;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t4. Bedeutung der Zonen\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div role=\"region tabpanel\" aria-labelledby=\"e-n-accordion-item-8921 e-n-tab-title-934581051\" id=\"e-n-tab-content-934581051\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-9f7648c e-con-full e-flex e-con e-child\" data-id=\"9f7648c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1afe7d elementor-widget__width-initial dce_masking-none elementor-widget elementor-widget-image\" data-id=\"c1afe7d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"510\" height=\"501\" src=\"https:\/\/gardeniser-academy.eu\/wp-content\/uploads\/2025\/03\/LP3_M3_img01.png\" class=\"attachment-large size-large wp-image-3719\" alt=\"\" srcset=\"https:\/\/gardeniser-academy.eu\/wp-content\/uploads\/2025\/03\/LP3_M3_img01.png 510w, https:\/\/gardeniser-academy.eu\/wp-content\/uploads\/2025\/03\/LP3_M3_img01-300x295.png 300w\" sizes=\"(max-width: 510px) 100vw, 510px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da36363 elementor-widget elementor-widget-text-editor\" data-id=\"da36363\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Laut David Holmgren, dem Mitbegr\u00fcnder der Permakultur, \u201e<i>zeigt die Permakultur-Blume die wichtigsten Bereiche, die einer Transformation bed\u00fcrfen, um eine nachhaltige Kultur zu schaffen.<\/i>\u201c Jedes Bl\u00fctenblatt bzw. jeder Bereich der Permakultur-Blume steht f\u00fcr eine Kategorie, in der Permakultur-Prinzipien angewendet werden k\u00f6nnen. Wenn man sich jedoch auf ein Bl\u00fctenblatt konzentriert, st\u00f6\u00dft man immer auch auf Aspekte aller anderen Bereiche. Diese Vernetzung bedeutet, dass man in jeder Kategorie Elemente findet, die mit allen anderen in Zusammenhang stehen.  <\/p><p>Diese Eigenschaft macht die Permakulturblume so wertvoll. Ob es sich um etwas Allgemeines wie die Landwirtschaft oder um etwas Spezielles wie ein Solarmodul handelt, jedes Thema spiegelt gleichzeitig Aspekte aller Bereiche wider. Die Blume veranschaulicht daher die verschiedenen Dimensionen eines jeden Themas und ermutigt uns, unsere Entw\u00fcrfe zu verbessern, indem wir uns im Rahmen unserer Arbeit mit jedem Bereich auseinandersetzen.  <\/p><p>Die Auswirkungen der Permakultur sind oft am deutlichsten in den Bereichen Land, Geb\u00e4ude und Werkzeuge und Technologie sichtbar \u2013 also in den Bereichen, die die physische Welt direkt pr\u00e4gen. Weniger offensichtlich ist sie in den Bereichen Bildung und Kultur, Gesundheit und spirituelles Wohlbefinden, Finanzen und Wirtschaft sowie Landbesitz und Gemeindeverwaltung. Diese letztgenannten Bereiche, die manchmal als \u201eunsichtbare Strukturen\u201c oder, vielleicht genauer, als soziale Systeme bezeichnet werden, weisen Muster auf, die oft \u00fcbersehen werden, aber dennoch von entscheidender Bedeutung sind. Ein unterentwickeltes Blattwerk beeintr\u00e4chtigt jedes System, und kein einzelnes \u00fcberentwickeltes Blattwerk kann die anderen ausgleichen.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region tabpanel\" aria-labelledby=\"e-n-accordion-item-8921 e-n-tab-title-934581052\" id=\"e-n-tab-content-934581052\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-e370534 e-con-full e-flex e-con e-child\" data-id=\"e370534\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d38367b elementor-widget__width-initial dce_masking-none elementor-widget elementor-widget-image\" data-id=\"d38367b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"472\" height=\"478\" src=\"https:\/\/gardeniser-academy.eu\/wp-content\/uploads\/2025\/03\/LP3_M3_img02.png\" class=\"attachment-large size-large wp-image-3724\" alt=\"\" srcset=\"https:\/\/gardeniser-academy.eu\/wp-content\/uploads\/2025\/03\/LP3_M3_img02.png 472w, https:\/\/gardeniser-academy.eu\/wp-content\/uploads\/2025\/03\/LP3_M3_img02-296x300.png 296w\" sizes=\"(max-width: 472px) 100vw, 472px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b666711 elementor-widget elementor-widget-text-editor\" data-id=\"b666711\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><i>In Permaculture: Principles and Pathways Beyond Sustainability I<\/i><\/b>, stellt David Holmgren die drei ethischen Grundprinzipien der Permakultur vor: <b>Earth Care, People Care, und Fair Share<\/b>. Diese ethischen Grunds\u00e4tze dienen als Leitlinie f\u00fcr alle Permakultur-Prinzipien und bilden einen zusammenh\u00e4ngenden Rahmen f\u00fcr ein nachhaltiges, ausgewogenes Leben. <\/p><p>In dieser \u00dcbersicht wird die Verbindung zwischen Holmgrens Gestaltungsprinzipien und diesen ethischen Grundwerten untersucht und aufgezeigt, wie jedes Prinzip die Ethik der F\u00fcrsorge f\u00fcr die Erde, die F\u00f6rderung des Gemeinwohls und die Gew\u00e4hrleistung einer gerechten Ressourcenverteilung unterst\u00fctzt.<\/p><p>Das Zusammenspiel dieser ethischen Werte und Prinzipien unterstreicht einen ganzheitlichen Ansatz, der menschliches Handeln mit \u00f6kologischen Werten in Einklang bringt und so die Widerstandsf\u00e4higkeit und ein nachhaltiges Zusammenleben f\u00f6rdert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ede44ca elementor-widget elementor-widget-n-accordion\" data-id=\"ede44ca\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2490\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-2490\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Erhaltung der Erde (Ethik 1) <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-2490\" class=\"elementor-element elementor-element-dbc8862 e-con-full e-flex e-con e-child\" data-id=\"dbc8862\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a587df2 elementor-widget elementor-widget-text-editor\" data-id=\"a587df2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Grundprinzipien<\/strong>: Beobachten und interagieren, Energie einfangen und speichern, erneuerbare Ressourcen und Dienstleistungen nutzen und wertsch\u00e4tzen.<\/p><p><strong>Zusammenhang<\/strong>: Die Beobachtung nat\u00fcrlicher Muster, die Nutzung von Solarenergie und die Priorisierung erneuerbarer Ressourcen sind wesentliche Schritte zur Sicherung der langfristigen Gesundheit der Erde.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2491\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2491\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> F\u00fcrsorge f\u00fcr Menschen (Ethik 2) <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-2491\" class=\"elementor-element elementor-element-3fa2948 e-con-full e-flex e-con e-child\" data-id=\"3fa2948\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b3ee865 elementor-widget elementor-widget-text-editor\" data-id=\"b3ee865\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Schl\u00fcsselprinzipien<\/strong>: Erziele eine Rendite, wende Selbstregulierung an und akzeptiere Feedback, nutze Kanten und sch\u00e4tze den Randbereich.<\/p><p><strong>Verbindung<\/strong>: Die Unterst\u00fctzung von Projekten, die greifbare Vorteile bieten, der Aufbau anpassungsf\u00e4higer Systeme und die Wertsch\u00e4tzung von \u201eRandbereichen\u201c stehen alle im Einklang mit der F\u00fcrsorge f\u00fcr Einzelpersonen und Gemeinschaften.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2492\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2492\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Fairer Anteil (Ethik 3) <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-2492\" class=\"elementor-element elementor-element-e56740d e-con-full e-flex e-con e-child\" data-id=\"e56740d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59066e1 elementor-widget elementor-widget-text-editor\" data-id=\"59066e1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Schl\u00fcsselprinzipien<\/strong>: Vielfalt nutzen und wertsch\u00e4tzen, kleine und langsame L\u00f6sungen nutzen, Kanten nutzen und Randbereiche wertsch\u00e4tzen, kreativ nutzen und auf Ver\u00e4nderungen reagieren.<\/p><p><strong>Verbindung<\/strong>: Die F\u00f6rderung von Vielfalt, schrittweise Entwicklung und innovative Reaktionen auf Ver\u00e4nderungen unterst\u00fctzen den gerechten Zugang zu Ressourcen und gew\u00e4hrleisten eine gerechte Verteilung in der Gemeinschaft.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b37da39 elementor-widget elementor-widget-text-editor\" data-id=\"b37da39\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Die Integration dieser Prinzipien und ethischen Grunds\u00e4tze bildet einen umfassenden Ansatz f\u00fcr nachhaltiges Design und Ressourcenmanagement, der die Harmonie zwischen Natur, Menschen und eine gerechte Verteilung f\u00fcr alle betont.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region tabpanel\" aria-labelledby=\"e-n-accordion-item-8921 e-n-tab-title-934581053\" id=\"e-n-tab-content-934581053\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\" elementor-element elementor-element-43523c2 e-con-full e-flex e-con e-child\" data-id=\"43523c2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6854abb dce_masking-none elementor-widget elementor-widget-image\" data-id=\"6854abb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"666\" src=\"https:\/\/gardeniser-academy.eu\/wp-content\/uploads\/2025\/03\/LP3_M3_img03.png\" class=\"attachment-large size-large wp-image-3729\" alt=\"\" srcset=\"https:\/\/gardeniser-academy.eu\/wp-content\/uploads\/2025\/03\/LP3_M3_img03.png 1000w, https:\/\/gardeniser-academy.eu\/wp-content\/uploads\/2025\/03\/LP3_M3_img03-300x250.png 300w, https:\/\/gardeniser-academy.eu\/wp-content\/uploads\/2025\/03\/LP3_M3_img03-768x640.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20c6818 elementor-widget elementor-widget-text-editor\" data-id=\"20c6818\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die 12 Permakultur-Prinzipien, die von David Holmgren in <i>Permakultur: Prinzipien und Wege jenseits der Nachhaltigkeit entwickelt wurden<\/i>, bieten einen umfassenden Leitfaden f\u00fcr die Schaffung von Systemen, die sowohl nachhaltig als auch harmonisch sind. Diese Prinzipien gehen \u00fcber die Standard-Umweltgestaltung hinaus und verk\u00f6rpern einen ganzheitlichen Ansatz f\u00fcr die Interaktion des Menschen mit der Welt. <\/p><p>Diese in der Permakultur-Philosophie verwurzelten Prinzipien gelten nicht nur f\u00fcr die Kultivierung produktiver G\u00e4rten, sondern auch f\u00fcr die Entwicklung eines Lebensstils und einer Denkweise, die tief in der Nachhaltigkeit verankert sind. Jedes Prinzip steht im Einklang mit den grundlegenden ethischen Prinzipien der Permakultur \u2013 Earth Care, People Care und Fair Share \u2013 und schafft ein vernetztes Rahmenwerk, das unsere Beziehung zur Natur verbessert, das Wohlbefinden f\u00f6rdert und die Gleichberechtigung der Ressourcen sicherstellt. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f0cdfc elementor-widget elementor-widget-n-accordion\" data-id=\"4f0cdfc\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8280\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-8280\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 1. Beobachten und interagieren <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-8280\" class=\"elementor-element elementor-element-a50390d e-con-full e-flex e-con e-child\" data-id=\"a50390d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5eb86a elementor-widget elementor-widget-text-editor\" data-id=\"f5eb86a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li aria-level=\"1\">Erl\u00e4uterung: Eine aufmerksame Beobachtung und Auseinandersetzung mit der Natur sind f\u00fcr jedes Permakulturprojekt von grundlegender Bedeutung. Bevor wir Ma\u00dfnahmen ergreifen, m\u00fcssen wir zun\u00e4chst die einzigartigen Muster, Abl\u00e4ufe und Dynamiken einer Umgebung verstehen, um L\u00f6sungen zu entwickeln, die auf ihre spezifischen Bed\u00fcrfnisse zugeschnitten sind.  <\/li><li aria-level=\"1\">Beispiel: Bevor du einen Garten gestaltest, beobachte die Wetterverh\u00e4ltnisse, die Sonneneinstrahlung und die Wechselwirkungen zwischen den Pflanzen, um die Anordnung der Nutzpflanzen zu planen und das Mikroklima zu optimieren.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8281\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8281\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 2. Energie auffangen und speichern <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-8281\" class=\"elementor-element elementor-element-4adfd54 e-con-full e-flex e-con e-child\" data-id=\"4adfd54\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30f8c13 elementor-widget elementor-widget-text-editor\" data-id=\"30f8c13\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Explanation: This principle emphasizes capturing resources when they are most abundant to ensure a reliable supply over time. <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Example: Install solar panels to harness and store energy during sunny days, ensuring a power source when sunlight is unavailable.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8282\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8282\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 3. Ernte <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-8282\" class=\"elementor-element elementor-element-967a28f e-con-full e-flex e-con e-child\" data-id=\"967a28f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9a57e7 elementor-widget elementor-widget-text-editor\" data-id=\"b9a57e7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Erl\u00e4uterung: Durch die Priorisierung von Projekten, die einen sinnvollen Ertrag erzielen, wird sichergestellt, dass unsere Bem\u00fchungen zu greifbaren Vorteilen f\u00fchren. <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Beispiel: Pflege eines Gartens, der nahrhafte Produkte liefert und sowohl pers\u00f6nliche Zufriedenheit als auch eine frische, lokale Lebensmittelversorgung bietet.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8283\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8283\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 4. Selbstregulierung anwenden und Feedback akzeptieren <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-8283\" class=\"elementor-element elementor-element-b26f3fb e-flex e-con-boxed e-con e-child\" data-id=\"b26f3fb\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6cb687b elementor-widget elementor-widget-text-editor\" data-id=\"6cb687b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Erl\u00e4uterung: Systeme sollten so konzipiert sein, dass sie sich selbst regulieren und anpassen und flexibel auf R\u00fcckmeldungen reagieren. <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Beispiel: Einf\u00fchrung von Wassersparma\u00dfnahmen und Anpassung des Verbrauchs auf der Grundlage von \u00dcberwachung und R\u00fcckmeldungen, um eine nachhaltige Wassernutzung zu f\u00f6rdern.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8284\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8284\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 5. Nutzung und Wertsch\u00e4tzung erneuerbarer Ressourcen und Dienstleistungen <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-8284\" class=\"elementor-element elementor-element-5838301 e-flex e-con-boxed e-con e-child\" data-id=\"5838301\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86e3fa5 elementor-widget elementor-widget-text-editor\" data-id=\"86e3fa5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Erl\u00e4uterung: Die Bevorzugung erneuerbarer Ressourcen verringert die Abh\u00e4ngigkeit von nicht erneuerbaren Ressourcen und unterst\u00fctzt die langfristige Nachhaltigkeit. <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Beispiel: Entscheide dich f\u00fcr erneuerbare Energiequellen wie Wind- oder Wasserkraft anstelle von fossilen Brennstoffen, um die Umweltbelastung zu minimieren.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8285\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8285\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 6. Produziere keinen Abfall <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-8285\" class=\"elementor-element elementor-element-e2d8528 e-flex e-con-boxed e-con e-child\" data-id=\"e2d8528\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8c1990 elementor-widget elementor-widget-text-editor\" data-id=\"d8c1990\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Erl\u00e4uterung: Nimm eine Denkweise an, die jede Ressource wertsch\u00e4tzt, Abfall minimiert und die Effizienz maximiert. <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Beispiel: Richte ein Kompostierungssystem ein, um organischen Abfall in n\u00e4hrstoffreichen Boden zu recyceln, Abfall zu reduzieren und die Bodengesundheit zu verbessern.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8286\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8286\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 7. Entwerfe von Mustern bis zu Details <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-8286\" class=\"elementor-element elementor-element-5f99400 e-flex e-con-boxed e-con e-child\" data-id=\"5f99400\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-871be46 elementor-widget elementor-widget-text-editor\" data-id=\"871be46\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Erl\u00e4uterung: Beginne damit, \u00fcbergreifende Muster in Natur und Gesellschaft zu verstehen und sie als Grundlage f\u00fcr detailliertere Gestaltungsdetails zu nutzen. <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Beispiel: Untersuche in der Stadtplanung den Verkehrsfluss und das Sozialverhalten, bevor du Stra\u00dfen und \u00f6ffentliche Pl\u00e4tze gestaltest, um eine funktionale Umgebung zu schaffen.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8287\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"8\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8287\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 8. Integrieren statt Segregieren <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-8287\" class=\"elementor-element elementor-element-a9fd21c e-flex e-con-boxed e-con e-child\" data-id=\"a9fd21c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2699370 elementor-widget elementor-widget-text-editor\" data-id=\"2699370\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Erl\u00e4uterung: Designelemente sollten harmonisch zusammenwirken und sich innerhalb eines koh\u00e4renten Systems gegenseitig unterst\u00fctzen und f\u00f6rdern. <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Beispiel: Verwende Begleitpflanzungen in der Landwirtschaft, um Nutzpflanzen anzubauen, die sich gegenseitig beim Wachstum unterst\u00fctzen und so die Bodenfruchtbarkeit und Sch\u00e4dlingsbek\u00e4mpfung auf nat\u00fcrliche Weise verbessern.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8288\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"9\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8288\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 9. Verwende kleine und langsame L\u00f6sungen <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-8288\" class=\"elementor-element elementor-element-6f76a52 e-flex e-con-boxed e-con e-child\" data-id=\"6f76a52\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a31fba elementor-widget elementor-widget-text-editor\" data-id=\"0a31fba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Erl\u00e4uterung: Kleine, schrittweise aufgebaute Systeme sind oft einfacher zu warten, besser an die lokalen Ressourcen angepasst und nachhaltiger. <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Beispiel: Verwende im Gartenbau langsam freigesetzte organische D\u00fcngemittel, um die Bodengesundheit zu f\u00f6rdern und den N\u00e4hrstoffabfluss zu reduzieren.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8289\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"10\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8289\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 10. Vielfalt nutzen und sch\u00e4tzen <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-8289\" class=\"elementor-element elementor-element-a4d3f5e e-flex e-con-boxed e-con e-child\" data-id=\"a4d3f5e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c2d7cf elementor-widget elementor-widget-text-editor\" data-id=\"1c2d7cf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Erl\u00e4uterung: Vielfalt erh\u00f6ht die Widerstandsf\u00e4higkeit eines Systems, indem sie es weniger anf\u00e4llig f\u00fcr Bedrohungen macht und eine Vielzahl von St\u00e4rken erschlie\u00dft. <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Beispiel: Bei der Entwicklung einer Gemeinschaft sollte eine Mischung aus F\u00e4higkeiten und Perspektiven gef\u00f6rdert werden, um ein anpassungsf\u00e4higes und widerstandsf\u00e4higes Umfeld zu schaffen.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-82810\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"11\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-82810\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 11. Verwende und sch\u00e4tze die R\u00e4nder <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-82810\" class=\"elementor-element elementor-element-23edfe4 e-flex e-con-boxed e-con e-child\" data-id=\"23edfe4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b07efd9 elementor-widget elementor-widget-text-editor\" data-id=\"b07efd9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Erl\u00e4uterung: Randzonen sind oft Orte, an denen einzigartige, produktive Interaktionen stattfinden, und sollten aufgrund ihres Potenzials gesch\u00e4tzt werden. <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Beispiel: Im Landschaftsbau sollten Randzonen zwischen verschiedenen Vegetationstypen geschaffen werden, um die Biodiversit\u00e4t zu f\u00f6rdern und n\u00fctzliche Wildtiere zu unterst\u00fctzen.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-82811\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"12\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-82811\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 12. Ver\u00e4nderungen kreativ nutzen und auf sie reagieren <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-82811\" class=\"elementor-element elementor-element-bd0007c e-flex e-con-boxed e-con e-child\" data-id=\"bd0007c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0233eeb elementor-widget elementor-widget-text-editor\" data-id=\"0233eeb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Erl\u00e4uterung: Nimm Ver\u00e4nderungen als Chance wahr und reagiere durchdacht und proaktiv auf sich entwickelnde Systemdynamiken. <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Beispiel: Wende im Gesch\u00e4ftsleben agile Praktiken an, die eine schnelle Anpassung an Marktver\u00e4nderungen erm\u00f6glichen und so die Widerstandsf\u00e4higkeit und Nachhaltigkeit f\u00f6rdern.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff80221 elementor-widget elementor-widget-text-editor\" data-id=\"ff80221\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Jedes Prinzip erfasst einen einzigartigen Aspekt des permakulturellen Denkens und bietet eine Anleitung zur Schaffung von Systemen, die die Erde respektieren, die Gesundheit der Gemeinschaft in den Vordergrund stellen und eine faire Ressourcennutzung f\u00f6rdern. Wenn wir diese Prinzipien erforschen, gewinnen wir Erkenntnisse f\u00fcr den Aufbau einer widerstandsf\u00e4higeren, ausgewogeneren Zukunft. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region tabpanel\" aria-labelledby=\"e-n-accordion-item-8921 e-n-tab-title-934581054\" id=\"e-n-tab-content-934581054\" data-tab-index=\"4\" style=\"--n-tabs-title-order: 4;\" class=\" elementor-element elementor-element-f4b63e9 e-con-full e-flex e-con e-child\" data-id=\"f4b63e9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa80bd4 elementor-widget elementor-widget-text-editor\" data-id=\"aa80bd4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Zonen bieten eine strukturierte M\u00f6glichkeit, Gestaltungselemente in einer menschlichen Umgebung zu organisieren, basierend auf der H\u00e4ufigkeit ihrer Nutzung durch Menschen und den Bed\u00fcrfnissen von Pflanzen oder Tieren. <\/span><\/p><p><span style=\"font-weight: 400;\">Dies ist der Wohnbereich oder der zentrale Wohnbereich. Hier zielen die Prinzipien der Permakultur darauf ab, den Energie- und Wasserverbrauch zu minimieren, nat\u00fcrliche Ressourcen wie das Sonnenlicht zu nutzen und eine nachhaltige, harmonische Umgebung zum Leben und Arbeiten zu schaffen. Zone 0 ist informell definiert und in Bill Mollisons Buch nicht explizit beschrieben.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7380e83 elementor-widget elementor-widget-n-accordion\" data-id=\"7380e83\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1210\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1210\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Zone 0 <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-1210\" class=\"elementor-element elementor-element-185eff9 e-con-full e-flex e-con e-child\" data-id=\"185eff9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67f1541 elementor-widget elementor-widget-text-editor\" data-id=\"67f1541\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dies ist der Wohnbereich oder der zentrale Wohnbereich. Hier zielen die Prinzipien der Permakultur darauf ab, den Energie- und Wasserverbrauch zu minimieren, nat\u00fcrliche Ressourcen wie das Sonnenlicht zu nutzen und eine nachhaltige, harmonische Umgebung zum Leben und Arbeiten zu schaffen. Zone 0 ist informell definiert und in Bill Mollisons Buch nicht explizit beschrieben.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1211\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1211\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Zone 1 <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-1211\" class=\"elementor-element elementor-element-6230583 e-con-full e-flex e-con e-child\" data-id=\"6230583\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-976bc92 elementor-widget elementor-widget-text-editor\" data-id=\"976bc92\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Diese Zone befindet sich in der N\u00e4he des Hauses und beherbergt Elemente, die h\u00e4ufig gepflegt werden m\u00fcssen oder t\u00e4glich zug\u00e4nglich sein m\u00fcssen, wie Salatpflanzen, Kr\u00e4uter, Beerenobst wie Erdbeeren oder Himbeeren, Gew\u00e4chsh\u00e4user und Kompostbeh\u00e4lter f\u00fcr K\u00fcchenabf\u00e4lle. Hier werden h\u00e4ufig Hochbeete verwendet, insbesondere in st\u00e4dtischen Umgebungen. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1212\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1212\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Zone 2 <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-1212\" class=\"elementor-element elementor-element-a0c9fca e-con-full e-flex e-con e-child\" data-id=\"a0c9fca\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d89dcf elementor-widget elementor-widget-text-editor\" data-id=\"4d89dcf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Zone 2 unterst\u00fctzt mehrj\u00e4hrige Pflanzen, die weniger regelm\u00e4\u00dfige Pflege ben\u00f6tigen, wie z. B. Beschneiden oder gelegentliches Unkrautj\u00e4ten. Sie kann Johannisbeerstr\u00e4ucher, Obstg\u00e4rten, K\u00fcrbisse und Bienenst\u00f6cke sowie gr\u00f6\u00dfere Kompostbeh\u00e4lter umfassen. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1213\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1213\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Zone 3 <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-1213\" class=\"elementor-element elementor-element-0c7033c e-flex e-con-boxed e-con e-child\" data-id=\"0c7033c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-760dec6 elementor-widget elementor-widget-text-editor\" data-id=\"760dec6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Dies ist das Hauptanbaugebiet f\u00fcr Nutzpflanzen, die sowohl f\u00fcr den Eigenbedarf als auch f\u00fcr den Handel bestimmt sind. Einmal etabliert, ben\u00f6tigen diese Pflanzen nur minimale Pflege, wie z. B. w\u00f6chentliches Gie\u00dfen oder Unkrautj\u00e4ten, wenn Mulchen und andere Techniken angewendet werden. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1214\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1214\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Zone 4 <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-1214\" class=\"elementor-element elementor-element-60977a3 e-flex e-con-boxed e-con e-child\" data-id=\"60977a3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-562c8a8 elementor-widget elementor-widget-text-editor\" data-id=\"562c8a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Zone 4 ist ein halbwildes Gebiet, das f\u00fcr die Nahrungssuche, das Sammeln von Wildpflanzen und die Gewinnung von Bau- oder Brennholz vorgesehen ist.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1215\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1215\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Zone 5 <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-8921 e-n-accordion-item-1215\" class=\"elementor-element elementor-element-79deb4d e-flex e-con-boxed e-con e-child\" data-id=\"79deb4d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc81de7 elementor-widget elementor-widget-text-editor\" data-id=\"fc81de7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zone 5 ist ein echtes Wildnisgebiet ohne menschliche Eingriffe und dient der Beobachtung nat\u00fcrlicher \u00d6kosysteme. Sie dient als R\u00fcckzugsgebiet f\u00fcr n\u00fctzliche Bakterien, Schimmelpilze und Insekten, die andere Zonen unterst\u00fctzen k\u00f6nnen. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ab5651 elementor-widget elementor-widget-text-editor\" data-id=\"4ab5651\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lasst uns aktiv werden! Unter Ber\u00fccksichtigung aller bisher durchgef\u00fchrten Aktivit\u00e4ten und der neuen Werkzeuge und \u00dcberlegungen, die die Permakultur-Prinzipien bieten, werdet ihr euer Projekt und die Gestaltung des Gemeinschaftsgartens selbst definieren. Ihr werdet in verschiedenen Phasen drei Dokumente ausf\u00fcllen oder entwerfen m\u00fcssen.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9d44da elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d9d44da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: 1rem; text-align: var(--text-align); font-weight: var( --e-global-typography-text-font-weight );\">Wenn du noch kein Land f\u00fcr deinen Garten hast, musst du deine Suchkriterien festlegen<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac6c331 elementor-align-center elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"ac6c331\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/gardeniser-academy.eu\/de\/lp3_m3_l2_a1\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kriterien f\u00fcr die Durchsuchung des Grundst\u00fccks<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-636ae55 elementor-widget elementor-widget-text-editor\" data-id=\"636ae55\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Verwende die <a href=\"https:\/\/ouidoo.ch\/en\/la-methode-obredim-design-permaculture-organisation-ressource-evaluation-bordure\/\">OBREDIM-methode<\/a><\/span><span style=\"font-weight: 400;\">um eine Diagnose \u00fcber das Land des Gartens zu erstellen<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8749e53 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8749e53\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/gardeniser-academy.eu\/de\/lp3_m3_l2_a2\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Die Diagnose des Landes<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a80c52 elementor-widget elementor-widget-text-editor\" data-id=\"4a80c52\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Erstelle ein Modell des Gemeinschaftsgartens<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b324941 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b324941\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/gardeniser-academy.eu\/de\/lp3_m3_l2_a3\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Das Gartenmodell<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8922\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8922\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> L3. Die Verbindungen, Die Uns Vereinen - Erstellt die Satzung f\u00fcr euren Gemeinschaftsgarten  <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8922\" class=\"elementor-element elementor-element-9eebe9a e-con-full e-flex e-con e-child\" data-id=\"9eebe9a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0330d94 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"0330d94\" data-element_type=\"widget\" data-settings=\"{&quot;tabs_justify_horizontal&quot;:&quot;stretch&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"3345812\" aria-label=\"Tabs. Open items with Enter or Space, close with Escape and navigate using the Arrow keys.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-33458121\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-33458121\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tT1. Definition unserer gemeinsamen Werte \u2013 Was ist ein Wert? \t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-33458122\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-33458122\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tT2. Das Projektdokument \t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div role=\"region tabpanel\" aria-labelledby=\"e-n-accordion-item-8922 e-n-tab-title-33458121\" id=\"e-n-tab-content-33458121\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-d8e378b e-con-full e-flex e-con e-child\" data-id=\"d8e378b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75f3435 elementor-widget elementor-widget-text-editor\" data-id=\"75f3435\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Eine Wertecharta ist<\/span> <b>ein feierliches Dokument, das die Philosophie, Vision und Verpflichtungen der Organisation darlegt. <\/b><span style=\"font-weight: 400;\">. Es handelt sich um ein offizielles Dokument, das nicht vorgeschrieben ist (aber dringend empfohlen wird), das die DNA des Gemeinschaftsgartens wiedergibt und seine Werte formalisiert.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Jetzt ist es an der Zeit, eure eigene Charta zu verfassen!&nbsp; Laden Sie die unten stehende Aktivit\u00e4t herunter, um sie zu bearbeiten.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-960569a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"960569a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/gardeniser-academy.eu\/de\/lp3_m3_l3_a1\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Die Charta Ihres Gemeinschaftsgartens<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06bf02e elementor-widget elementor-widget-text-editor\" data-id=\"06bf02e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Um dich zu inspirieren, kannst du das beigef\u00fcgte Beispiel f\u00fcr Gemeinschaftsg\u00e4rten herunterladen. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85eb924 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"85eb924\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/gardeniser-academy.eu\/de\/example-charter\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download Example Charter<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region tabpanel\" aria-labelledby=\"e-n-accordion-item-8922 e-n-tab-title-33458122\" id=\"e-n-tab-content-33458122\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-ff31fe2 e-con-full e-flex e-con e-child\" data-id=\"ff31fe2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf9f9c4 elementor-widget elementor-widget-text-editor\" data-id=\"bf9f9c4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Das Projektdokument vereint mehrere Schl\u00fcsselelemente, die als Leitfaden f\u00fcr die Einrichtung und Verwaltung eines Gemeinschaftsgartens dienen. Es besteht haupts\u00e4chlich aus: <\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">dem Rahmendokument, <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">dem Gartenmodell <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">der Charta des Gemeinschaftsgartens.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00e2669 elementor-widget elementor-widget-text-editor\" data-id=\"00e2669\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Zur Erinnerung:<\/span><\/p><p><b>Das Projektdokument<\/b><span style=\"font-weight: 400;\"> Das Rahmendokument strukturiert die wesentlichen Aspekte des Gemeinschaftsgartens. Es enth\u00e4lt eine allgemeine Beschreibung des Projekts, der allgemeinen Ziele und der geplanten Aktivit\u00e4ten. Es identifiziert die erforderlichen Ressourcen und erstellt einen vorl\u00e4ufigen Finanzplan. Es untersucht m\u00f6gliche rechtliche Rahmenbedingungen und legt einen allgemeinen Zeitplan f\u00fcr die Fertigstellung fest.   <\/span><\/p><p><b>Das Gartenmodell <\/b><span style=\"font-weight: 400;\">Das Gartenmodell ist eine visuelle Darstellung in Form eines 3D-Plans oder -Diagramms, das den geplanten Aufbau veranschaulicht. Es definiert die verschiedenen Zonen (einzelne Parzellen, Gemeinschaftsbereiche, Kompostierungszonen usw.). <\/span><\/p><p><span style=\"font-weight: 400;\">Schlie\u00dflich ,<\/span><b>legt die Satzung des Gemeinschaftsgartens<\/b><span style=\"font-weight: 400;\"> die Philosophie, die Vision und die Verpflichtungen der Organisation fest.<\/span><\/p><p><span style=\"font-weight: 400;\">Durch die Zusammenf\u00fchrung dieser drei Dokumente wird das<\/span> <b>Projektdokument <\/b><span style=\"font-weight: 400;\">zu einer globalen Referenz f\u00fcr alle Beteiligten, sowohl intern als auch extern, und gew\u00e4hrleistet, dass sich der Gemeinschaftsgarten koh\u00e4rent und in \u00dcbereinstimmung mit den festgelegten Grunds\u00e4tzen entwickelt.<\/span><\/p><p><span style=\"font-weight: 400;\">Wir empfehlen, das Projektdokument so zu pr\u00e4sentieren, dass es von allen Beteiligten eingesehen und abgerufen werden kann, entweder in Papierform oder in elektronischer Form (z. B. PDF).<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8923\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8923\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Modul-Quiz <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8923\" class=\"elementor-element elementor-element-3e90b93 e-flex e-con-boxed e-con e-child\" data-id=\"3e90b93\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8923\" class=\"elementor-element elementor-element-f15b813 e-con-full e-flex e-con e-child\" data-id=\"f15b813\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85a4d45 elementor-widget elementor-widget-shortcode\" data-id=\"85a4d45\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"h5p-iframe-wrapper\"><iframe id=\"h5p-iframe-70\" class=\"h5p-iframe\" data-content-id=\"70\" style=\"height:1px\" src=\"about:blank\" frameBorder=\"0\" scrolling=\"no\" title=\"Quiz LP3 M3 DE\"><\/iframe><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-4298","module","type-module","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/gardeniser-academy.eu\/de\/wp-json\/wp\/v2\/module\/4298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gardeniser-academy.eu\/de\/wp-json\/wp\/v2\/module"}],"about":[{"href":"https:\/\/gardeniser-academy.eu\/de\/wp-json\/wp\/v2\/types\/module"}],"version-history":[{"count":5,"href":"https:\/\/gardeniser-academy.eu\/de\/wp-json\/wp\/v2\/module\/4298\/revisions"}],"predecessor-version":[{"id":5980,"href":"https:\/\/gardeniser-academy.eu\/de\/wp-json\/wp\/v2\/module\/4298\/revisions\/5980"}],"wp:attachment":[{"href":"https:\/\/gardeniser-academy.eu\/de\/wp-json\/wp\/v2\/media?parent=4298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}